{"id":125,"count":1,"description":"","link":"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/","name":"professionally","slug":"professionally","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/journalrepo.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/journalrepo.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/index.php\\\/tag\\\/professionally\\\/#listItem\",\"name\":\"professionally\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/index.php\\\/tag\\\/professionally\\\/#listItem\",\"position\":2,\"name\":\"professionally\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/journalrepo.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/#collectionpage\",\"url\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/\",\"name\":\"professionally - Journaling for Mindful Living\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/journalrepo.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/#organization\",\"name\":\"journalrepo.com\",\"url\":\"https:\\\/\\\/journalrepo.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/journalrepo.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/1.png\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/#organizationLogo\",\"width\":226,\"height\":64},\"image\":{\"@id\":\"https:\\\/\\\/journalrepo.com\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/125\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/journalrepo.com\\\/#website\",\"url\":\"https:\\\/\\\/journalrepo.com\\\/\",\"name\":\"journalrepo.com\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/journalrepo.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"professionally - Journaling for Mindful Living","description":"","canonical_url":"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/journalrepo.com#listItem","position":1,"name":"Home","item":"https:\/\/journalrepo.com","nextItem":{"@type":"ListItem","@id":"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/#listItem","name":"professionally"}},{"@type":"ListItem","@id":"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/#listItem","position":2,"name":"professionally","previousItem":{"@type":"ListItem","@id":"https:\/\/journalrepo.com#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/#collectionpage","url":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/","name":"professionally - Journaling for Mindful Living","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/journalrepo.com\/#website"},"breadcrumb":{"@id":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/journalrepo.com\/#organization","name":"journalrepo.com","url":"https:\/\/journalrepo.com\/","logo":{"@type":"ImageObject","url":"https:\/\/journalrepo.com\/wp-content\/uploads\/2024\/01\/1.png","@id":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/#organizationLogo","width":226,"height":64},"image":{"@id":"https:\/\/journalrepo.com\/wp-json\/wp\/v2\/tags\/125\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/journalrepo.com\/#website","url":"https:\/\/journalrepo.com\/","name":"journalrepo.com","inLanguage":"en-GB","publisher":{"@id":"https:\/\/journalrepo.com\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/journalrepo.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tprofessionally\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/journalrepo.com"},{"label":"professionally","link":"https:\/\/journalrepo.com\/index.php\/tag\/professionally\/"}],"_links":{"self":[{"href":"https:\/\/journalrepo.com\/index.php\/wp-json\/wp\/v2\/tags\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/journalrepo.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/journalrepo.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/journalrepo.com\/index.php\/wp-json\/wp\/v2\/posts?tags=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}